{"id":92,"date":"2024-04-08T15:45:48","date_gmt":"2024-04-08T13:45:48","guid":{"rendered":"https:\/\/brave-dialog.de\/?page_id=92"},"modified":"2024-06-30T12:49:15","modified_gmt":"2024-06-30T10:49:15","slug":"impressum","status":"publish","type":"page","link":"https:\/\/brave-dialog.de\/en\/impressum\/","title":{"rendered":"Imprint"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; link_font=&#8220;Cuprum Regular|||||||#F4801E|dotted&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2>Impressum<\/h2>\n<p>&nbsp;<\/p>\n<h3>Angaben gem\u00e4\u00df \u00a7 5 TMG<\/h3>\n<p>Christiane Windhausen<br \/>Erasmusstra\u00dfe 15<br \/>D-40223 D\u00fcsseldorf<\/p>\n<h3>Kontakt<\/h3>\n<p>Telefon: +49-173-5102425<br \/>E-Mail: hello@brave-dialog.de<\/p>\n<h3>Umsatzsteuer-ID<\/h3>\n<p>Gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz: DE 114103514<\/p>\n<h3>EU-Streitschlichtung<\/h3>\n<p>Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS) bereit: <a href=\"https:\/\/ec.europa.eu\/consumers\/\" target=\"_blank\" rel=\"noopener\">https:\/\/ec.europa.eu\/consumers\/<\/a><\/p>\n<h3>Verbraucher\u00adstreit\u00adbeilegung \/ Universal\u00adschlichtungs\u00adstelle<\/h3>\n<p>Wir nehmen an einem Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teil. Zust\u00e4ndig ist die Universalschlichtungsstelle des Zentrums f\u00fcr Schlichtung e.V., Stra\u00dfburger Stra\u00dfe 8, 77694 Kehl am Rhein (<a href=\"https:\/\/www.verbraucher-schlichter.de\" target=\"_blank\" rel=\"noopener\">https:\/\/www.verbraucher-schlichter.de<\/a>).<\/p>\n<h3>Haftung f\u00fcr Inhalte<\/h3>\n<p>Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen.<\/p>\n<p>Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.<\/p>\n<h3>Haftung f\u00fcr Links<\/h3>\n<p>Unser Angebot enth\u00e4lt Links zu externen Websites Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar.<\/p>\n<p>Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<\/p>\n<h3>Urheberrecht<\/h3>\n<p>Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind nur f\u00fcr den privaten, nicht kommerziellen Gebrauch gestattet.<\/p>\n<p>Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen.<\/p>\n<p>Quelle: <a href=\"https:\/\/www.e-recht24.de\/impressum-generator.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.e-recht24.de\/impressum-generator.html<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impressum &nbsp; Angaben gem\u00e4\u00df \u00a7 5 TMG Christiane WindhausenErasmusstra\u00dfe 15D-40223 D\u00fcsseldorf Kontakt Telefon: +49-173-5102425E-Mail: hello@brave-dialog.de Umsatzsteuer-ID Gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz: DE 114103514 EU-Streitschlichtung Die Europ\u00e4ische Kommission stellt eine Plattform zur Online-Streitbeilegung (OS) bereit: https:\/\/ec.europa.eu\/consumers\/ Verbraucher\u00adstreit\u00adbeilegung \/ Universal\u00adschlichtungs\u00adstelle Wir nehmen an einem Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teil. Zust\u00e4ndig ist die Universalschlichtungsstelle des Zentrums f\u00fcr Schlichtung e.V., Stra\u00dfburger Stra\u00dfe 8, 77694 Kehl am Rhein (https:\/\/www.verbraucher-schlichter.de). Haftung f\u00fcr Inhalte Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen. Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen. Haftung f\u00fcr Links Unser Angebot enth\u00e4lt Links zu externen Websites Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-92","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/brave-dialog.de\/en\/wp-json\/wp\/v2\/pages\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brave-dialog.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brave-dialog.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brave-dialog.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brave-dialog.de\/en\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":0,"href":"https:\/\/brave-dialog.de\/en\/wp-json\/wp\/v2\/pages\/92\/revisions"}],"wp:attachment":[{"href":"https:\/\/brave-dialog.de\/en\/wp-json\/wp\/v2\/media?parent=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}